{"id":9577,"count":1,"description":"","link":"https:\/\/www.healthsrainbow.com\/blog\/tag\/bone-marrow-disorders\/","name":"Bone Marrow Disorders","slug":"bone-marrow-disorders","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.healthsrainbow.com\/blog\/wp-json\/wp\/v2\/tags\/9577"}],"collection":[{"href":"https:\/\/www.healthsrainbow.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.healthsrainbow.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.healthsrainbow.com\/blog\/wp-json\/wp\/v2\/posts?tags=9577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}